{"id":62,"count":0,"description":"","link":"https:\/\/fahrdiensthelden.com\/en\/tag\/europe-en\/","name":"Europe","slug":"europe-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Europe Archive - Fahrdiensthelden GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fahrdiensthelden.com\/en\/tag\/europe-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Europe Archive - Fahrdiensthelden GmbH\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fahrdiensthelden.com\/en\/tag\/europe-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Fahrdiensthelden GmbH\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/fahrdiensthelden.com\\\/en\\\/tag\\\/europe-en\\\/\",\"url\":\"https:\\\/\\\/fahrdiensthelden.com\\\/en\\\/tag\\\/europe-en\\\/\",\"name\":\"Europe Archive - Fahrdiensthelden GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fahrdiensthelden.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fahrdiensthelden.com\\\/en\\\/tag\\\/europe-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fahrdiensthelden.com\\\/en\\\/tag\\\/europe-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/fahrdiensthelden.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Europe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fahrdiensthelden.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fahrdiensthelden.com\\\/en\\\/\",\"name\":\"Fahrdiensthelden GmbH\",\"description\":\"Krankenfahrten - Rollstuhlfahrten - Flughafentransfer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fahrdiensthelden.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Europe Archive - Fahrdiensthelden GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fahrdiensthelden.com\/en\/tag\/europe-en\/","og_locale":"en_US","og_type":"article","og_title":"Europe Archive - Fahrdiensthelden GmbH","og_url":"https:\/\/fahrdiensthelden.com\/en\/tag\/europe-en\/","og_site_name":"Fahrdiensthelden GmbH","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fahrdiensthelden.com\/en\/tag\/europe-en\/","url":"https:\/\/fahrdiensthelden.com\/en\/tag\/europe-en\/","name":"Europe Archive - Fahrdiensthelden GmbH","isPartOf":{"@id":"https:\/\/fahrdiensthelden.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/fahrdiensthelden.com\/en\/tag\/europe-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/fahrdiensthelden.com\/en\/tag\/europe-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/fahrdiensthelden.com\/en\/"},{"@type":"ListItem","position":2,"name":"Europe"}]},{"@type":"WebSite","@id":"https:\/\/fahrdiensthelden.com\/en\/#website","url":"https:\/\/fahrdiensthelden.com\/en\/","name":"Fahrdiensthelden GmbH","description":"Krankenfahrten - Rollstuhlfahrten - Flughafentransfer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fahrdiensthelden.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/fahrdiensthelden.com\/en\/wp-json\/wp\/v2\/tags\/62","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fahrdiensthelden.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/fahrdiensthelden.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/fahrdiensthelden.com\/en\/wp-json\/wp\/v2\/posts?tags=62"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}